{"id":1184,"date":"2026-04-30T01:03:41","date_gmt":"2026-04-30T01:03:41","guid":{"rendered":"https:\/\/glennruscoe.physio\/newswebsite2\/2026\/04\/30\/uma-revisao-sistematica-constatou-que-programas-de-exercicios-ministrados-em-video-podem-melhorar-o-desempenho-fisico\/"},"modified":"2026-04-30T01:03:41","modified_gmt":"2026-04-30T01:03:41","slug":"uma-revisao-sistematica-constatou-que-programas-de-exercicios-ministrados-em-video-podem-melhorar-o-desempenho-fisico","status":"publish","type":"post","link":"https:\/\/glennruscoe.physio\/newswebsite2\/2026\/04\/30\/uma-revisao-sistematica-constatou-que-programas-de-exercicios-ministrados-em-video-podem-melhorar-o-desempenho-fisico\/","title":{"rendered":"Uma revis\u00e3o sistem\u00e1tica constatou que programas de exerc\u00edcios ministrados em v\u00eddeo podem melhorar o desempenho f\u00edsico"},"content":{"rendered":"<div class=\"wprt-container\">\n<div class=\"ewa-rteLine\">\n<div class=\"ewa-rteLine\">Uma revis\u00e3o sistem\u00e1tica constatou que programas de exerc\u00edcios ministrados por v\u00eddeo podem melhorar o desempenho f\u00edsico, particularmente a for\u00e7a dos membros inferiores, o equil\u00edbrio e a mobilidade em idosos com 60 anos ou mais que vivem na comunidade, mas h\u00e1 incertezas quanto ao seu efeito na taxa de quedas, no n\u00famero de pessoas que caem e no medo de cair.\u00a0Esta revis\u00e3o sistem\u00e1tica e meta-an\u00e1lise teve como objetivo sintetizar as evid\u00eancias e avaliar o efeito de programas de exerc\u00edcios ministrados por meio de v\u00eddeos instrucionais, em compara\u00e7\u00e3o com a aus\u00eancia de exerc\u00edcios ou interven\u00e7\u00f5es de controle sem exerc\u00edcios, sobre o desempenho f\u00edsico e as quedas em idosos com 60 anos ou mais que vivem na comunidade.<\/div>\n<\/div>\n<p>\u00a0<\/p>\n<div><\/div>\n<div class=\"ewa-rteLine\"><span><strong>M\u00e9todos<\/strong><\/span><\/div>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\">Foram pesquisadas sete bases de dados, incluindo MEDLINE, EMBASE, CINAHL, PsycINFO, o Registro Central Cochrane de Ensaios Controlados, TRIP e PEDro, em busca de ensaios cl\u00ednicos randomizados (ECR) publicados em ingl\u00eas. A pesquisa tamb\u00e9m incluiu literatura cinzenta para identificar material de pesquisa n\u00e3o publicado, acessado por meio do Ethos e do ProQuest. Os artigos completos foram analisados por dois revisores independentemente, e as diverg\u00eancias foram resolvidas por meio de discuss\u00e3o com um terceiro revisor. Os estudos eleg\u00edveis inclu\u00edram idosos residentes na comunidade com idade \u2265 60 anos e ensaios que utilizaram programas de exerc\u00edcios com v\u00eddeos instrucionais pr\u00e9-gravados (online ou offline) para demonstrar a pr\u00e1tica de exerc\u00edcios, em compara\u00e7\u00e3o com nenhuma interven\u00e7\u00e3o de exerc\u00edcio ou uma interven\u00e7\u00e3o controle sem exerc\u00edcio (por exemplo, folhetos, links para sites de promo\u00e7\u00e3o da atividade f\u00edsica ou diretrizes de atividade f\u00edsica). Os exerc\u00edcios baseados em v\u00eddeo poderiam ser complementados por visitas domiciliares ou intera\u00e7\u00f5es presenciais com profissionais. O desfecho prim\u00e1rio foi o desempenho f\u00edsico, avaliado como uma medida \u00fanica do desempenho f\u00edsico geral, bem como de componentes individuais, incluindo for\u00e7a dos membros inferiores, equil\u00edbrio e mobilidade. Os desfechos secund\u00e1rios foram vari\u00e1veis relacionadas a quedas, incluindo n\u00famero de quedas, n\u00famero de pessoas que ca\u00edram e medo de cair. Os revisores contataram os autores para obter informa\u00e7\u00f5es adicionais sobre dados faltantes. O risco de vi\u00e9s foi avaliado pelo primeiro autor utilizando a Ferramenta de Avalia\u00e7\u00e3o de Risco de Vi\u00e9s da Cochrane, e a qualidade da evid\u00eancia foi avaliada utilizando o sistema GRADE (Grading of Recommendations, Assessment, Development and Evaluation). Ambas as avalia\u00e7\u00f5es foram ent\u00e3o revisadas e resolvidas por meio de discuss\u00e3o em equipe at\u00e9 que se chegasse a um consenso. A metan\u00e1lise foi conduzida utilizando um modelo de efeitos aleat\u00f3rios devido \u00e0 heterogeneidade da popula\u00e7\u00e3o, das medidas e das interven\u00e7\u00f5es, e somente quando pelo menos tr\u00eas estudos estavam dispon\u00edveis para compara\u00e7\u00e3o por desfecho.<\/div>\n<div><\/div>\n<p>\u00a0<\/p>\n<div class=\"ewa-rteLine\"><span><strong>Resultados \u2013 ensaios inclu\u00eddos<\/strong><\/span><\/div>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\">\n<div class=\"ewa-rteLine\">Dezesseis ensaios cl\u00ednicos, envolvendo 1910 participantes, foram inclu\u00eddos. A idade m\u00e9dia dos participantes variou de 67 a 90 anos, e todos eram idosos residentes na comunidade. Um ensaio cl\u00ednico incluiu apenas participantes do sexo feminino, enquanto quinze inclu\u00edram participantes de ambos os sexos, embora dois tivessem menos participantes do sexo feminino. Todos os estudos implementaram exerc\u00edcios multicomponentes incorporando for\u00e7a e equil\u00edbrio. Cinco ensaios cl\u00ednicos adicionaram exerc\u00edcios de flexibilidade, tr\u00eas adicionaram exerc\u00edcios de tarefas funcionais, tr\u00eas adicionaram exerc\u00edcios de resist\u00eancia e um adicionou exerc\u00edcios de mobiliza\u00e7\u00e3o articular. Dez ensaios cl\u00ednicos utilizaram v\u00eddeos de exerc\u00edcios pr\u00e9-gravados offline, em DVDs ou fitas VHS, enquanto seis utilizaram a plataforma online, por meio de smartphones, aplicativos ou sites. Oito ensaios cl\u00ednicos compararam exerc\u00edcios ministrados por v\u00eddeo com interven\u00e7\u00f5es sem exerc\u00edcios, enquanto oito compararam com a aus\u00eancia de interven\u00e7\u00e3o.<\/div>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\">A frequ\u00eancia do programa de exerc\u00edcios variou de di\u00e1ria a cinco vezes por semana; mais comumente, duas a tr\u00eas vezes por semana em onze ensaios cl\u00ednicos, diariamente em tr\u00eas ensaios cl\u00ednicos, cinco vezes por semana em um ensaio cl\u00ednico e n\u00e3o especificada em um ensaio cl\u00ednico. A dura\u00e7\u00e3o do acompanhamento da interven\u00e7\u00e3o variou de um m\u00eas a dois anos. Mais comumente, seis meses em cinco tentativas, um m\u00eas em duas tentativas, dois meses em uma tentativa, tr\u00eas meses em duas tentativas, quatro meses em duas tentativas, cinco meses em uma tentativa, doze meses em duas tentativas e vinte e quatro meses em uma tentativa.<\/div>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\">Dos ensaios inclu\u00eddos, tr\u00eas apresentaram baixo risco de vi\u00e9s, seis suscitaram algumas preocupa\u00e7\u00f5es e sete apresentaram alto risco de vi\u00e9s.<\/div>\n<div><\/div>\n<\/div>\n<div>A meta-an\u00e1lise mostrou que programas de exerc\u00edcios ministrados por meio de v\u00eddeos instrucionais pr\u00e9-gravados melhoraram a for\u00e7a dos membros inferiores (DMP = 0,35, IC 95% 0,11 a 0,59, n = 1165, 9 ensaios, I\u00b2 = 70,35%, p &lt; 0,001), o equil\u00edbrio (DMP = 0,45, IC 95% 0,07 a 0,83, n = 959, 7 ensaios, I\u00b2 = 85,07%, p = 0,02), a mobilidade (DM = 0,96, IC 95% 0,46 a 1,46, n = 891, 5 ensaios, I\u00b2 = 53,31%, p &lt; 0,001) e o desempenho f\u00edsico geral (DMP = 0,36, IC 95% 0,17 a 0,56, n = 531, 4 ensaios, I\u00b2 = 13,49%, p&lt;0,001) em compara\u00e7\u00e3o com o grupo controle.<\/div>\n<div><\/div>\n<p>\u00a0<\/p>\n<div class=\"ewa-rteLine\"><span><strong>Resultados<\/strong><\/span><\/div>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\">\n<div class=\"ewa-rteLine\">A metan\u00e1lise n\u00e3o revelou diferen\u00e7a no medo de quedas ao comparar programas de exerc\u00edcios com v\u00eddeo ao grupo controle. Apenas 3 estudos relataram a taxa de quedas e o n\u00famero de participantes que ca\u00edram, o que foi insuficiente para a metan\u00e1lise. Eventos adversos menores foram relatados em seis estudos, sem eventos adversos maiores.<\/div>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\">Utilizando a abordagem GRADE, a certeza da evid\u00eancia foi moderada para for\u00e7a dos membros inferiores, mobilidade e desempenho f\u00edsico geral, baixa para equil\u00edbrio e muito baixa para medo de quedas. A certeza da evid\u00eancia foi rebaixada se mais de 25% dos ensaios inclu\u00eddos apresentassem alto risco de vi\u00e9s, se houvesse heterogeneidade estat\u00edstica ou intervalo de confian\u00e7a amplo e\/ou se houvesse menos de 400 participantes.<\/div>\n<\/div>\n<p>\u00a0<\/p>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\"><span><strong>Conclus\u00e3o<\/strong><\/span><\/div>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\">Evid\u00eancias de baixa a moderada qualidade sugerem que programas de exerc\u00edcios ministrados por v\u00eddeo podem melhorar efetivamente o desempenho f\u00edsico, incluindo for\u00e7a dos membros inferiores, equil\u00edbrio e mobilidade, em idosos que vivem na comunidade. No entanto, o efeito desses programas sobre quedas, n\u00famero de quedas e medo de cair permanece incerto, pois poucos estudos relataram esses desfechos e as evid\u00eancias dispon\u00edveis s\u00e3o de muito baixa certeza.<\/div>\n<p>\u00a0<\/p>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\">Adliah F, et al. Effects of exercise programmes delivered using video technology on physical performance and falls in people aged 60 years and over living in the community: a systematic review and meta-analysis. <em>BMJ Open<\/em>. 2025 Apr, 15:e092775. DOI: 10.1136\/bmjopen-2024-092775<\/div>\n<p>\u00a0<\/p>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\"><a href=\"https:\/\/search.pedro.org.au\/search-results\/record-detail\/82891\">Leia mais no PEDro<\/a>.<\/div>\n<div><\/div>\n<div><\/div>\n<\/div>\n<p>The post <a href=\"https:\/\/pedro.org.au\/portuguese\/uma-revisao-sistematica-constatou-que-programas-de-exercicios-ministrados-em-video-podem-melhorar-o-desempenho-fisico\/\">Uma revis\u00e3o sistem\u00e1tica constatou que programas de exerc\u00edcios ministrados em v\u00eddeo podem melhorar o desempenho f\u00edsico<\/a> appeared first on <a href=\"https:\/\/pedro.org.au\/\">PEDro<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Uma revis\u00e3o sistem\u00e1tica constatou que programas de exerc\u00edcios ministrados por v\u00eddeo podem melhorar o desempenho f\u00edsico, particularmente a for\u00e7a dos membros inferiores, o equil\u00edbrio e a mobilidade em idosos com 60 anos ou mais que vivem na comunidade, mas h\u00e1&#8230;<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"_ti_tpc_template_sync":false,"_ti_tpc_template_id":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-1184","post","type-post","status-publish","format-standard","hentry","category-physio"],"_links":{"self":[{"href":"https:\/\/glennruscoe.physio\/newswebsite2\/wp-json\/wp\/v2\/posts\/1184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glennruscoe.physio\/newswebsite2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/glennruscoe.physio\/newswebsite2\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/glennruscoe.physio\/newswebsite2\/wp-json\/wp\/v2\/comments?post=1184"}],"version-history":[{"count":0,"href":"https:\/\/glennruscoe.physio\/newswebsite2\/wp-json\/wp\/v2\/posts\/1184\/revisions"}],"wp:attachment":[{"href":"https:\/\/glennruscoe.physio\/newswebsite2\/wp-json\/wp\/v2\/media?parent=1184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/glennruscoe.physio\/newswebsite2\/wp-json\/wp\/v2\/categories?post=1184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/glennruscoe.physio\/newswebsite2\/wp-json\/wp\/v2\/tags?post=1184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}